{"id":5484,"date":"2021-06-15T01:38:16","date_gmt":"2021-06-14T23:38:16","guid":{"rendered":"https:\/\/www.wolfsberg-judoclub.at\/?p=5484"},"modified":"2021-06-15T01:38:16","modified_gmt":"2021-06-14T23:38:16","slug":"internationales-judoturnier-in-maribor","status":"publish","type":"post","link":"https:\/\/www.wolfsberg-judoclub.at\/2021\/06\/internationales-judoturnier-in-maribor\/","title":{"rendered":"Internationales Judoturnier in Maribor"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\">250 Judok\u00e4mpfer aus Slowenien, Kroatien und \u00d6sterreich k\u00e4mpften beim 60.<br \/>Int. Judoturnier in Maribor.<br \/>Nach 14 Monaten Wettkampfpause aufgrund der Coronapandemie, war es das<br \/>erste Judoturnier f\u00fcr eine Standortbestimmung. In \u00d6sterreich startet die<br \/>Turniersaison mit der \u00d6sterreichischen Meisterschaft f\u00fcr U18 Ende Juni.<br \/>F\u00fcr Batuchan Jusupov, Gewinner von 11 Int. Turnieren im Jahr 2019, Mitglied<br \/>des \u00d6sterreichischen Jugendkaders U16, vom Judoclub Long Life Wolfsberg,<br \/>war es die einzige M\u00f6glichkeit ein Turnier vor der \u00d6M U18 zu bestreiten. Die<br \/>U18 dient auch zur Vorbereitung zum eigentlichen Leistungsh\u00f6hepunkt der<br \/>\u00d6sterreichischen Meisterschaft U16 Anfang Oktober.<br \/>In Maribor k\u00e4mpfte Batuchan Jusupov in der Klasse -55kg betreut durch Trainer<br \/>J\u00fcrgen Rossmann. Er gewann gegen Pintaric, JC Maribor mit Festhaltetechnik,<br \/>gegen Kramberger, JC Maribor mit Wurftechnik, gegen Ude, JC Polyteam mit<br \/>Wurftechnik und verlor im Finalkampf gegen Blasiz, JC Eleznikar mit einer<br \/>Kontertechnik.<br \/>Silbermedaille zum Start der Turnierwettk\u00e4mpfe nach der langen Pause mit<br \/>eingeschr\u00e4nkten Trainingsm\u00f6glichkeiten, ein Top \u2013 Ergebnis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>250 Judok\u00e4mpfer aus Slowenien, Kroatien und \u00d6sterreich k\u00e4mpften beim 60.Int. Judoturnier in Maribor.Nach 14 Monaten Wettkampfpause aufgrund der Coronapandemie, war es daserste Judoturnier f\u00fcr eine Standortbestimmung. In \u00d6sterreich startet dieTurniersaison mit der \u00d6sterreichischen Meisterschaft f\u00fcr U18 Ende Juni.F\u00fcr Batuchan Jusupov,&#8230;<br \/><a class=\"read-more-button\" href=\"https:\/\/www.wolfsberg-judoclub.at\/2021\/06\/internationales-judoturnier-in-maribor\/\">Mehr Lesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":5485,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/posts\/5484"}],"collection":[{"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/comments?post=5484"}],"version-history":[{"count":1,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/posts\/5484\/revisions"}],"predecessor-version":[{"id":5486,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/posts\/5484\/revisions\/5486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/media\/5485"}],"wp:attachment":[{"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/media?parent=5484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/categories?post=5484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/tags?post=5484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}