{"id":4066,"date":"2015-11-23T14:15:50","date_gmt":"2015-11-23T12:15:50","guid":{"rendered":"http:\/\/www.wolfsberg-judoclub.at\/?p=4066"},"modified":"2018-08-23T11:43:24","modified_gmt":"2018-08-23T09:43:24","slug":"newaza-turnier-in-treffen","status":"publish","type":"post","link":"https:\/\/www.wolfsberg-judoclub.at\/2015\/11\/newaza-turnier-in-treffen\/","title":{"rendered":"Newaza Turnier in Treffen"},"content":{"rendered":"<p>Der Judoclub SV Treffen veranstaltete im Auftrag des Judolandesverbandes K\u00e4rnten das Judo Newaza Turnier. 48 Starter aus 10 K\u00e4rntner Vereinen waren am Start.<br \/>\nDas Besondere an diesem Turnier ist, dass ausschlie\u00dflich am Boden gek\u00e4mpft wird. Gerade diese Besonderheit lockte eine gro\u00dfe Starterzahl und Publikum in die Hauptschule Gegendtal nach Treffen. Junge und \u00c4ltere sowie Erfahrene und Neueinsteiger erfreuten sich an diesem besonderen Turnier. Im Newaza kann ein Judoka den Kampf durch eine Osaekomi (Festhaltetechnik), einer Shimewaza (W\u00fcrgetechnik) oder durch eine Kansetzuwaza (Hebeltechnik) f\u00fcr sich entscheiden.<\/p>\n<p>Der ASK\u00d6 Judoclub Longlife Wolfsberg erk\u00e4mpfte sich als erfolgreichster Verein bei diesem Turnier, zwei Goldmedaillen, zwei Silbermedaillen und 1 Bronzemedaille, vor dem Judo Verein Velden 2\/1\/3, und dem ESV St. Veit 2\/1\/0.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Judoclub SV Treffen veranstaltete im Auftrag des Judolandesverbandes K\u00e4rnten das Judo Newaza Turnier. 48 Starter aus 10 K\u00e4rntner Vereinen waren am Start. Das Besondere an diesem Turnier ist, dass ausschlie\u00dflich am Boden gek\u00e4mpft wird. Gerade diese Besonderheit lockte eine&#8230;<br \/><a class=\"read-more-button\" href=\"https:\/\/www.wolfsberg-judoclub.at\/2015\/11\/newaza-turnier-in-treffen\/\">Mehr Lesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":4067,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/posts\/4066"}],"collection":[{"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/comments?post=4066"}],"version-history":[{"count":3,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/posts\/4066\/revisions"}],"predecessor-version":[{"id":4917,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/posts\/4066\/revisions\/4917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/media\/4067"}],"wp:attachment":[{"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/media?parent=4066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/categories?post=4066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wolfsberg-judoclub.at\/wp-json\/wp\/v2\/tags?post=4066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}